{"id":8529,"date":"2024-04-05T16:25:44","date_gmt":"2024-04-05T05:25:44","guid":{"rendered":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins.jpg"},"modified":"2024-04-05T16:25:44","modified_gmt":"2024-04-05T05:25:44","slug":"ben-mcgee-and-shaun-higgins","status":"inherit","type":"attachment","link":"https:\/\/www.otva.com\/blog\/8525-2\/ben-mcgee-and-shaun-higgins\/","title":{"rendered":"Ben McGee and Shaun Higgins"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-8529","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/aaMOfU-2dz","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=300%2C135&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=1536%2C691&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=2048%2C922&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?w=2160&amp;ssl=1 2160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"8529\" data-permalink=\"https:\/\/www.otva.com\/blog\/8525-2\/ben-mcgee-and-shaun-higgins\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=2560%2C1152&amp;ssl=1\" data-orig-size=\"2560,1152\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;SM-A515F&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1712235795&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.6&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Ben McGee and Shaun Higgins\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=720%2C324&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1152,"file":"2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg","filesize":371180,"sizes":{"medium":{"file":"Ben-McGee-and-Shaun-Higgins-300x135.jpg","width":300,"height":135,"filesize":50738,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=300%2C135&ssl=1"},"large":{"file":"Ben-McGee-and-Shaun-Higgins-1024x461.jpg","width":1024,"height":461,"filesize":115307,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=720%2C324&ssl=1"},"thumbnail":{"file":"Ben-McGee-and-Shaun-Higgins-150x150.jpg","width":150,"height":150,"filesize":45324,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"Ben-McGee-and-Shaun-Higgins-768x346.jpg","width":768,"height":346,"filesize":88363,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=720%2C324&ssl=1"},"lbsp_12_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-500x1800.jpg","width":500,"height":1800,"filesize":102831,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-500x1800.jpg"},"lbsp_346_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-400x1800.jpg","width":400,"height":1800,"filesize":81742,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-400x1800.jpg"},"lbsp_12_same_size_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-500x500.jpg","width":500,"height":500,"filesize":74804,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-500x500.jpg"},"lbsp_346_same_size_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-400x400.jpg","width":400,"height":400,"filesize":63895,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-400x400.jpg"},"rpgp_12_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-500x1800.jpg","width":500,"height":1800,"filesize":102831,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-500x1800.jpg"},"rpgp_346_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-400x1800.jpg","width":400,"height":1800,"filesize":81742,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-400x1800.jpg"},"rpgp_12_same_size_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-500x500.jpg","width":500,"height":500,"filesize":74804,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-500x500.jpg"},"rpgp_346_same_size_thumb":{"file":"Ben-McGee-and-Shaun-Higgins-400x400.jpg","width":400,"height":400,"filesize":63895,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-400x400.jpg"},"1536x1536":{"file":"Ben-McGee-and-Shaun-Higgins-1536x691.jpg","width":1536,"height":691,"filesize":182626,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=1536%2C691&ssl=1"},"2048x2048":{"file":"Ben-McGee-and-Shaun-Higgins-2048x922.jpg","width":2048,"height":922,"filesize":268309,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=2048%2C922&ssl=1"},"wl_media_sidebar_img":{"file":"Ben-McGee-and-Shaun-Higgins-54x54.jpg","width":54,"height":54,"filesize":41331,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=54%2C54&ssl=1"},"wl_media_blog_img":{"file":"Ben-McGee-and-Shaun-Higgins-800x400.jpg","width":800,"height":400,"filesize":94133,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=800%2C400&ssl=1"},"wl_blog_img":{"file":"Ben-McGee-and-Shaun-Higgins-350x150.jpg","width":350,"height":150,"filesize":53364,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?resize=350%2C150&ssl=1"},"full":{"file":"Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=2560%2C1152&ssl=1","width":2560,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg?fit=2560%2C1152&ssl=1"}},"image_meta":{"aperture":"2","credit":"","camera":"SM-A515F","caption":"","created_timestamp":"1712235795","copyright":"","focal_length":"4.6","iso":"160","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"original_image":"Ben-McGee-and-Shaun-Higgins.jpg"},"post":8525,"source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/04\/Ben-McGee-and-Shaun-Higgins-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media\/8529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/comments?post=8529"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8525,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/posts\/8525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}