{"id":8506,"date":"2024-03-25T08:44:52","date_gmt":"2024-03-24T21:44:52","guid":{"rendered":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png"},"modified":"2024-03-25T08:44:52","modified_gmt":"2024-03-24T21:44:52","slug":"obituary-phil-hastings-mar2024","status":"inherit","type":"attachment","link":"https:\/\/www.otva.com\/blog\/phillip-hastings-passed-away-16-3-2024-aged-77-years\/obituary-phil-hastings-mar2024\/","title":{"rendered":"Obituary &#8211; Phil Hastings Mar2024"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-8506","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/aaMOfU-2dc","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"206\" height=\"300\" src=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?fit=206%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?w=437&amp;ssl=1 437w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?resize=206%2C300&amp;ssl=1 206w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" data-attachment-id=\"8506\" data-permalink=\"https:\/\/www.otva.com\/blog\/phillip-hastings-passed-away-16-3-2024-aged-77-years\/obituary-phil-hastings-mar2024\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?fit=437%2C636&amp;ssl=1\" data-orig-size=\"437,636\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Obituary &amp;#8211; Phil Hastings Mar2024\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?fit=437%2C636&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":437,"height":636,"file":"2024\/03\/Obituary-Phil-Hastings-Mar2024.png","filesize":143091,"sizes":{"medium":{"file":"Obituary-Phil-Hastings-Mar2024-206x300.png","width":206,"height":300,"filesize":59745,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?fit=206%2C300&ssl=1"},"thumbnail":{"file":"Obituary-Phil-Hastings-Mar2024-150x150.png","width":150,"height":150,"filesize":23535,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?resize=150%2C150&ssl=1"},"lbsp_346_thumb":{"file":"Obituary-Phil-Hastings-Mar2024-400x636.png","width":400,"height":636,"filesize":113899,"mime_type":"image\/png","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024-400x636.png"},"lbsp_12_same_size_thumb":{"file":"Obituary-Phil-Hastings-Mar2024-437x500.png","width":437,"height":500,"filesize":114103,"mime_type":"image\/png","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024-437x500.png"},"lbsp_346_same_size_thumb":{"file":"Obituary-Phil-Hastings-Mar2024-400x400.png","width":400,"height":400,"filesize":125524,"mime_type":"image\/png","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024-400x400.png"},"rpgp_346_thumb":{"file":"Obituary-Phil-Hastings-Mar2024-400x636.png","width":400,"height":636,"filesize":113899,"mime_type":"image\/png","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024-400x636.png"},"rpgp_12_same_size_thumb":{"file":"Obituary-Phil-Hastings-Mar2024-437x500.png","width":437,"height":500,"filesize":114103,"mime_type":"image\/png","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024-437x500.png"},"rpgp_346_same_size_thumb":{"file":"Obituary-Phil-Hastings-Mar2024-400x400.png","width":400,"height":400,"filesize":125524,"mime_type":"image\/png","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024-400x400.png"},"wl_media_sidebar_img":{"file":"Obituary-Phil-Hastings-Mar2024-54x54.png","width":54,"height":54,"filesize":4165,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?resize=54%2C54&ssl=1"},"wl_media_blog_img":{"file":"Obituary-Phil-Hastings-Mar2024-437x400.png","width":437,"height":400,"filesize":56340,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?resize=437%2C400&ssl=1"},"wl_blog_img":{"file":"Obituary-Phil-Hastings-Mar2024-350x150.png","width":350,"height":150,"filesize":35782,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?resize=350%2C150&ssl=1"},"full":{"file":"Obituary-Phil-Hastings-Mar2024.png?fit=437%2C636&ssl=1","width":437,"height":636,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png?fit=437%2C636&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":8505,"source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2024\/03\/Obituary-Phil-Hastings-Mar2024.png","_links":{"self":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media\/8506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/comments?post=8506"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8505,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/posts\/8505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}