{"id":6786,"date":"2018-12-11T14:26:22","date_gmt":"2018-12-11T03:26:22","guid":{"rendered":"http:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg"},"modified":"2018-12-11T14:26:22","modified_gmt":"2018-12-11T03:26:22","slug":"des-kinnersley-kevin-hills-andrew-shaw","status":"inherit","type":"attachment","link":"https:\/\/www.otva.com\/blog\/otv-wa-agm-20-november-2018\/des-kinnersley-kevin-hills-andrew-shaw\/","title":{"rendered":"Des Kinnersley, Kevin Hills &#038; Andrew Shaw"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-6786","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/aaMOfU-1Ls","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"6786\" data-permalink=\"https:\/\/www.otva.com\/blog\/otv-wa-agm-20-november-2018\/des-kinnersley-kevin-hills-andrew-shaw\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;COOLPIX S3&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1542717848&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.8&quot;,&quot;iso&quot;:&quot;52&quot;,&quot;shutter_speed&quot;:&quot;0.016638935108153&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Des Kinnersley, Kevin Hills &amp;#038; Andrew Shaw\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=720%2C540&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":768,"file":"2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg","sizes":{"thumbnail":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=720%2C540&ssl=1"},"large":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=720%2C540&ssl=1"},"lbsp_12_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x768.jpg","width":500,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x768.jpg"},"lbsp_346_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x768.jpg","width":400,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x768.jpg"},"lbsp_12_same_size_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x500.jpg"},"lbsp_346_same_size_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x400.jpg"},"rpgp_12_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x768.jpg","width":500,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x768.jpg"},"rpgp_346_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x768.jpg","width":400,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x768.jpg"},"rpgp_12_same_size_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-500x500.jpg"},"rpgp_346_same_size_thumb":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw-400x400.jpg"},"wl_media_sidebar_img":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-54x54.jpg","width":54,"height":54,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?resize=54%2C54&ssl=1"},"wl_media_blog_img":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-800x400.jpg","width":800,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?resize=800%2C400&ssl=1"},"wl_blog_img":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw-350x150.jpg","width":350,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?resize=350%2C150&ssl=1"},"full":{"file":"Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=1024%2C768&ssl=1","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg?fit=1024%2C768&ssl=1"}},"image_meta":{"aperture":"3","credit":"","camera":"COOLPIX S3","caption":"","created_timestamp":"1542717848","copyright":"","focal_length":"5.8","iso":"52","shutter_speed":"0.016638935108153","title":"","orientation":"1","keywords":[]}},"post":6778,"source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2018\/12\/Des-Kinnersley-Kevin-Hills-Andrew-Shaw.jpg","_links":{"self":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media\/6786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/comments?post=6786"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6778,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/posts\/6778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}