{"id":5575,"date":"2017-01-11T16:07:25","date_gmt":"2017-01-11T05:07:25","guid":{"rendered":"http:\/\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg"},"modified":"2017-01-11T16:07:25","modified_gmt":"2017-01-11T05:07:25","slug":"ray-woods-retirement-1976","status":"inherit","type":"attachment","link":"https:\/\/www.otva.com\/blog\/ray-woods-retirement-doonside-1976-name-those-in-the-photo\/ray-woods-retirement-1976\/","title":{"rendered":"ray-woods-retirement-1976"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-5575","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/aaMOfU-1rV","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"127\" src=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?fit=300%2C127&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?w=2556&amp;ssl=1 2556w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?w=2160&amp;ssl=1 2160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"5575\" data-permalink=\"https:\/\/www.otva.com\/blog\/ray-woods-retirement-doonside-1976-name-those-in-the-photo\/ray-woods-retirement-1976\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?fit=2556%2C1083&amp;ssl=1\" data-orig-size=\"2556,1083\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ray-woods-retirement-1976\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?fit=720%2C305&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2556,"height":1083,"file":"2017\/01\/Ray-Woods-Retirement-1976.jpg","sizes":{"wl_media_sidebar_img":{"file":"Ray-Woods-Retirement-1976-54x54.jpg","width":54,"height":54,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?resize=54%2C54&ssl=1"},"wl_media_blog_img":{"file":"Ray-Woods-Retirement-1976-800x400.jpg","width":800,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?resize=800%2C400&ssl=1"},"wl_blog_img":{"file":"Ray-Woods-Retirement-1976-350x150.jpg","width":350,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?resize=350%2C150&ssl=1"},"full":{"file":"Ray-Woods-Retirement-1976.jpg?fit=2556%2C1083&ssl=1","width":2556,"height":1083,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg?fit=2556%2C1083&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5573,"source_url":"https:\/\/www.otva.com\/blog\/wp-content\/uploads\/2017\/01\/Ray-Woods-Retirement-1976.jpg","_links":{"self":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media\/5575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/comments?post=5575"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5573,"href":"https:\/\/www.otva.com\/blog\/wp-json\/wp\/v2\/posts\/5573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}